{"id":14226,"date":"2018-10-17T14:02:30","date_gmt":"2018-10-17T12:02:30","guid":{"rendered":"http:\/\/www.cklcomunicaciones.es\/?p=14226"},"modified":"2025-01-17T16:40:34","modified_gmt":"2025-01-17T15:40:34","slug":"noticias-info-ckl-no-2-214-17-10-18","status":"publish","type":"post","link":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/","title":{"rendered":"Noticias Info CKL n\u00ba 2.214-17\/10\/18"},"content":{"rendered":"<div id=\"pl-14226\"  class=\"panel-layout\" >\n<div id=\"pg-14226-0\"  class=\"panel-grid panel-no-style\"  data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;,&quot;cell_alignment&quot;:&quot;flex-start&quot;}\" >\n<div id=\"pgc-14226-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-14226-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<img decoding=\"async\" class=\"lazyload  wp-image-13726\" src=\"http:\/\/www.cklcomunicaciones.es\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg\" data-orig-src=\"http:\/\/www.cklcomunicaciones.es\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg\" alt=\"CKL_comunicacion con perspetiva de genero\" width=\"132\" height=\"132\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27132%27%20height%3D%27132%27%20viewBox%3D%270%200%20132%20132%27%3E%3Crect%20width%3D%27132%27%20height%3D%27132%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/cklcomunicaciones.es\/coop\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-150x150.jpg 150w, https:\/\/cklcomunicaciones.es\/coop\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg 300w, https:\/\/cklcomunicaciones.es\/coop\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-450x450.jpg 450w, https:\/\/cklcomunicaciones.es\/coop\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 132px) 100vw, 132px\" \/><\/p>\n<p id=\":eq\" class=\"hP\" tabindex=\"-1\" data-thread-perm-id=\"thread-f:1613308472235883637\" data-legacy-thread-id=\"16639f8200bf7c75\"><strong>El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Mujeres espa\u00f1olas con estudios, trabajo e hijos, personas en riesgo de pobreza-Ana Penyas, 1\u00aa mujer Premio Nacional del C\u00f3mic<\/strong><\/p>\n<p>[toggle type=\u00bbfirst\u00bb title=\u00bbConvocatorias\u00bb]<\/p>\n<ul>\n<li><a href=\"http:\/\/www.juntadeandalucia.es\/iam\/catalogo\/doc\/convocatorias\/2018-iam\/GR-jornada-trata-mujeres-y-ninas-fines-explotacion-sexual.pdf\">Jornada &#8216;La <\/a><a href=\"http:\/\/www.juntadeandalucia.es\/iam\/catalogo\/doc\/convocatorias\/2018-iam\/GR-jornada-trata-mujeres-y-ninas-fines-explotacion-sexual.pdf\">T<\/a><a href=\"http:\/\/www.juntadeandalucia.es\/iam\/catalogo\/doc\/convocatorias\/2018-iam\/GR-jornada-trata-mujeres-y-ninas-fines-explotacion-sexual.pdf\">rata de mujeres y ni\u00f1as con fines de explotaci\u00f3n sexual. Haciendo frente<\/a><a href=\"http:\/\/www.juntadeandalucia.es\/iam\/catalogo\/doc\/convocatorias\/2018-iam\/GR-jornada-trata-mujeres-y-ninas-fines-explotacion-sexual.pdf\">&#8216;<\/a>. Centro Provincial del Instituto Andaluz de la Mujer de Granada, Subdelegaci\u00f3n del Gobierno de Granada, Ayuntamiento de Granada y Diputaci\u00f3n de Granada. 18 de octubre de 2018<\/li>\n<li><u><a href=\"https:\/\/www.facebook.com\/83209308910\/photos\/a.83243883910\/10156593187923911\/?type=3&amp;theater\">Ruta <\/a><a href=\"https:\/\/www.facebook.com\/83209308910\/photos\/a.83243883910\/10156593187923911\/?type=3&amp;theater\">l<\/a><a href=\"https:\/\/www.facebook.com\/83209308910\/photos\/a.83243883910\/10156593187923911\/?type=3&amp;theater\">iteraria &#8216;Las grandes escritoras de Sevilla&#8217;<\/a>. Casa Tomada para la Biblioteca P\u00fablica Provincial de Sevilla. 20 de octubre de 2018<\/u><\/li>\n<li><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">III Jornadas <\/a><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">D<\/a><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">octorales de <\/a><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">I<\/a><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">nvestigaci\u00f3n <\/a><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">en Estudios de las Mujere<\/a><a href=\"https:\/\/canal.ugr.es\/convocatoria\/iii-jornadas-doctorales-de-investigacion-en-estudios-de-las-mujeres\/\">s &#8216;Estudios de las Mujeres, Discursos y Pr\u00e1cticas de G\u00e9nero&#8217;<\/a>. Instituto Universitario de Investigaci\u00f3n de Estudios de las Mujeres y de G\u00e9nero de la Universidad de Granada. 22 y 23 de noviembre de 2018.<\/li>\n<li><a href=\"http:\/\/www.marialaffitte.org\/noticia-278.html\">XI Encuentro Internacional de Mujeres Singulare<\/a><a href=\"http:\/\/www.marialaffitte.org\/noticia-278.html\">s &#8216;La lucha de las espa\u00f1olas por sus derechos. 100 a\u00f1os despu\u00e9s&#8217;<\/a>. Federaci\u00f3n Mar\u00eda Laffitte. Del 24 al 26 de octubre de 2018<\/li>\n<li><a href=\"http:\/\/cepaim.org\/event\/curso-dinamizadora-comunitaria-para-la-prevencion-de-la-violencia-de-genero-en-sevilla-saliradelante\/\">Curso &#8216;Dinamizadora <\/a><a href=\"http:\/\/cepaim.org\/event\/curso-dinamizadora-comunitaria-para-la-prevencion-de-la-violencia-de-genero-en-sevilla-saliradelante\/\">c<\/a><a href=\"http:\/\/cepaim.org\/event\/curso-dinamizadora-comunitaria-para-la-prevencion-de-la-violencia-de-genero-en-sevilla-saliradelante\/\">omunitaria <\/a><a href=\"http:\/\/cepaim.org\/event\/curso-dinamizadora-comunitaria-para-la-prevencion-de-la-violencia-de-genero-en-sevilla-saliradelante\/\">para la prevenci\u00f3n de la violencia de g\u00e9nero&#8217;<\/a>. Fundaci\u00f3n Cepaim. Del 23 de octubre al 22 de noviembre de 2018; plazo de inscripci\u00f3n hasta el 18 de octubre de 2018<\/li>\n<\/ul>\n<p>[\/toggle]<\/p>\n<p>[toggle type=\u00bbfirst\u00bb title=\u00bbComunicaci\u00f3n\u00bb]<\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/malaga-capital\/reconocido-medio-comunicacion-20181017000641-ntvo.html\">SUR, reconocido como medio de comunicaci\u00f3n m\u00e1s solidario con las &#8230;<\/a>&#8211; Sur Digital<\/p>\n<p><a href=\"https:\/\/www.clarin.com\/cultura\/cronista-alma-guillermoprieto-cree-internet-ofrece-potencial-ilimitado-periodismo_0_q2ZhX6yiF.html\">La cronista Alma Guillermoprieto cree que Internet ofrece un potencial &#8230;<\/a>&#8211; Clar\u00edn.com<\/p>\n<p><a href=\"https:\/\/www.elperiodicodearagon.com\/noticias\/aragon\/papel-medios-transmision-igualdad_1316569.html\">El papel de los medios en la transmisi\u00f3n de la igualdad<\/a>&#8211; El Peri\u00f3dico de Arag\u00f3n<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=88&amp;ved=0ahUKEwi5pbG2qI3eAhVKhqYKHTy8DlM4UBCpAgg7KAAwBw&amp;url=http%3A%2F%2Fwww.ambito.com%2F936651-mujeres-en-tecnologia-el-77-considera-que-tiene-mas-obstaculos-que-los-hombres-para-crecer-y-tener-exito&amp;usg=AOvVaw2EKIw10-pB_uBAUOPYpwcD\">Mujeres en tecnolog\u00eda: el 77% considera que tiene m\u00e1s obst\u00e1culos &#8230;<\/a>&#8211; Ambito.com<\/p>\n<p><a href=\"https:\/\/www.publico.es\/economia\/privacidad-facebook-recolectara-datos-nuevos-dispositivos-videollamada-hogar.html\">Facebook s\u00ed recolectar\u00e1 datos con sus nuevos dispositivos de videollamada para el hogar<\/a> &#8211; P\u00fablico<\/p>\n<p>[\/toggle]<\/p>\n<p>[toggle type=\u00bbfirst\u00bb title=\u00bbAndaluc\u00eda\u00bb]<\/p>\n<p><strong>Econom\u00eda y Empresas<\/strong><\/p>\n<p><a href=\"http:\/\/www.juntadeandalucia.es\/presidencia\/portavoz\/137352\/JuntadeAndalucia\/ConsejeriadeEmpleo\/PlanesdeEmpleo\/Mayoresde45\">58 millones m\u00e1s para los planes locales de empleo de mayores de 45 y 55 a\u00f1os<\/a>\u2013 Oficina del Portavoz<\/p>\n<p><a href=\"http:\/\/www.mujeremprendedora.net\/certinet-mejorara-competencias-digitales-jovenes\/\">Certinet mejorar\u00e1 las competencias digitales de las j\u00f3venes<\/a> \u2013 Mujeremprendedora.net<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=10&amp;ved=0ahUKEwjM0NHuro3eAhUJIcAKHSCPDo4QqQIIQCgAMAk&amp;url=https%3A%2F%2Fwww.utreraweb.com%2Fnoticias-de-utrera%2Feconomia%2F9738%2FUtrera-sera-sede-el-jueves-25-de-octubre-de-un-encuentro-provincial-de-mujeres-empresarias-%2F&amp;usg=AOvVaw2j8PF5bpHI8fR9TXEK-y-A\">Utrera ser\u00e1 sede el jueves 25 de octubre de un encuentro provincial de empresarias &#8230;<\/a>&#8211; UtreraWeb<\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/malaga-capital\/riesgo-exclusion-social-20181017000926-nt.html\">M\u00e1s riesgo de exclusi\u00f3n social y una pobreza cr\u00f3nica, escenario de la &#8230;<\/a>&#8211; Sur Digital<\/p>\n<p><strong>Actualidad<\/strong><\/p>\n<p><a href=\"http:\/\/www.juntadeandalucia.es\/presidencia\/portavoz\/137409\/SusanaDiaz\/presidentaJuntadeAndalucia\/FundacionJuanRamonGuillen\/LaRinconada\/Sevilla\/olivar\/PatrimonioMundialdelaUnesco\">D\u00edaz respalda convertir el olivar en Patrimonio Mundial de la Unesco<\/a> \u2013 Oficina del Portavoz<\/p>\n<p><a href=\"https:\/\/www.diariocordoba.com\/noticias\/cultura\/eutopia-muestra-dia-dia-12-mujeres-ambito-domestico_1257644.html\">Eutop\u00eda muestra el d\u00eda a d\u00eda de 12 mujeres en el \u00e1mbito dom\u00e9stico<\/a>&#8211; Diario C\u00f3rdoba<\/p>\n<p><a href=\"https:\/\/www.eldiario.es\/andalucia\/cadiz\/Mujeres-Algodonales_0_825568242.html\">\u00ab\u00bfY mi calle pa&#8217; cu\u00e1ndo?\u00bb: vecinas de un pueblo de C\u00e1diz reivindican &#8230;<\/a>&#8211; eldiario.es<\/p>\n<p><strong>Violencias<\/strong><\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=1&amp;ved=0ahUKEwjX09WMsI3eAhVlLsAKHeTFDucQqQIIJygAMAA&amp;url=https%3A%2F%2Fwww.diariodesevilla.es%2Fjuzgado_de_guardia%2Factualidad%2FGranada-inaugura-comisiones-coordinacion-violencia_0_1291971207.html&amp;usg=AOvVaw2gJMePgm6imOAwiyJ9aYxx\">Granada inaugura la creaci\u00f3n de comisiones de coordinaci\u00f3n contra la violencia de g\u00e9nero&#8230;<\/a>&#8211; Diario de Sevilla<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=28&amp;ved=0ahUKEwjvqc7Ero3eAhWqBcAKHXO-AZo4FBCpAgg7KAAwBw&amp;url=https%3A%2F%2Fandaluciainformacion.es%2Fcordoba%2F782014%2Fandalucia-encabeza-la-violencia-de-genero-en-espana%2F&amp;usg=AOvVaw312BxsxU6LQsmR1ShTcB2g\">Andaluc\u00eda encabeza la violencia de g\u00e9nero en Espa\u00f1a<\/a>&#8211; Andaluc\u00eda Informaci\u00f3n<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=21&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwj2vpPbqo3eAhUJIsAKHVsTAGU4FBCpAggmKAAwAA&amp;url=https%3A%2F%2Fwww.diariodesevilla.es%2Fjuzgado_de_guardia%2Factualidad%2Fdenuncias-violencia-Andalucia-segundo-trimestre_0_1291971141.html&amp;usg=AOvVaw2uvLfxADg6IYTxMXAjNUy8\">Un 2% menos de denuncias por violencia de g\u00e9nero en Andaluc\u00eda en el segundo trimestre &#8230;<\/a>&#8211; Diario de Sevilla<\/p>\n<p><strong>Ciencia y Cultura<\/strong><\/p>\n<p><u><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=http:\/\/www.rtve.es\/noticias\/20181016\/animales-sin-collar-liberacion-femenina-andalucia-ibsen\/1820240.shtml&amp;ct=ga&amp;cd=CAEYMyoTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNE3Fkzdo972bXCJ3Q-TLEWft4YbVQ\">Animales sin collar&#8217;: liberaci\u00f3n femenina en una Andaluc\u00eda de Ibsen <\/a><\/u>&#8211; Rtve<\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/culturas\/mujeres-escena-visibiliza-20181017000410-ntvo.html\">Mujeres en escena visibiliza las desigualdades de g\u00e9nero a trav\u00e9s del &#8230;<\/a>&#8211; Sur Digital<\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/malaga-capital\/exposicion-madres-ofrece-20181016220836-nt.html\">La exposici\u00f3n &#8216;Madres&#8217; ofrece un homenaje a mujeres que luchan &#8230;<\/a>&#8211; Sur Digital<\/p>\n<p><a href=\"http:\/\/www.diariojaen.es\/cultura\/animo-a-las-letras-femeninas-XB4737734\">\u00c1nimo a las letras femeninas<\/a> &#8211; Diario Ja\u00e9n<strong>\u00a0<\/strong><\/p>\n<p><strong>Deporte<\/strong><\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/deportes\/mas-deportes\/doble-reto-regreso-20181017204210-nt.html\">Un doble reto para el regreso del Waterpolo Marbella a Primera Divisi\u00f3n<\/a>&#8211; Sur Digital<\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/deportes\/mas-deportes\/marta-lopez-supercampeona-20181017202803-nt.html\">Marta L\u00f3pez, supercampeona de Ruman\u00eda y l\u00edder invicta en la liga<\/a>&#8211; Sur Digital<\/p>\n<p><a href=\"https:\/\/www.diariocordoba.com\/noticias\/deportes\/carlota-convertira-centro-baloncesto-femenino-andaluz_1257538.html\">La Carlota se convertir\u00e1 en centro del baloncesto femenino andaluz<\/a>&#8211; Diario C\u00f3rdoba<\/p>\n<p>[\/toggle]<\/p>\n<p>[toggle type=\u00bbfirst\u00bb title=\u00bbEstado\u00bb]<\/p>\n<p><strong>Institucional<\/strong><\/p>\n<p><u><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=http:\/\/www.eleconomista.es\/economia\/noticias\/9456282\/10\/18\/El-congreso-tramitara-la-ley-para-garantizar-la-presencia-equilibrada-de-mujeres-en-los-consejos-de-administracion.html&amp;ct=ga&amp;cd=CAEYEioTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNFY6v77CWfXgVEG89UOOGKc7glgBQ\">El Congreso tramitar\u00e1 la ley para garantizar la presencia equilibrada de mujeres en los consejos de administraci\u00f3n &#8230; <\/a><\/u>&#8211; elEconomista.es<strong>\u00a0<\/strong><\/p>\n<p><strong>Institucional-CCAA<\/strong><\/p>\n<p><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=http:\/\/www.eldigitaldelamancha.com\/2018\/10\/16\/el-gobierno-regional-avanza-en-la-igualdad-de-la-mujer-dando-ejemplo-con-leyes-como-el-estatuto-de-la-mujer-rural-que-vera-la-luz-esta-legislatura\/&amp;ct=ga&amp;cd=CAEYBSoUMTI1OTM1NTA2NTI1NDk5MDE0NzEyGWMwMzcyZWJjMmZlYWRhNTk6ZXM6ZXM6RVM&amp;usg=AFQjCNEGjXfJdjl9NS3cmzUL9yg7VlL4NA\">El Gobierno regional avanza en la igualdad de la mujer dando ejemplo con leyes como el Estatuto &#8230; <\/a>&#8211; El Digital De La Mancha<\/p>\n<p><a href=\"http:\/\/www.mujeremprendedora.net\/pozuelo-acoge-el-ii-congreso-de-empresarias-y-directivas\/\">Pozuelo acoge el II Congreso de Empresarias y Directivas<\/a>\u2013 Mujeremprendededora.net<\/p>\n<p><a href=\"http:\/\/www.mujeremprendedora.net\/coordinadas-analizara-liderazgo-mujer-escuela-universidad-empresa-familia\/\">Coordinadas analizar\u00e1 el liderazgo de la mujer en la escuela, universidad, empresa y familia<\/a>\u2013 Mujeremprendededora.net<\/p>\n<p><strong>Econom\u00eda y Empresa<\/strong><\/p>\n<p><u><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=http:\/\/www.elmundo.es\/espana\/2018\/10\/16\/5bc5c45846163feb6f8b4620.html&amp;ct=ga&amp;cd=CAEYLioTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNF0rO9qIQe55JVmjMgvgB2i9oRgZA\">As\u00ed son las personas en riesgo de pobreza en Espa\u00f1a: mujeres espa\u00f1olas con estudios, trabajo e &#8230; <\/a><\/u>&#8211; El Mundo<\/p>\n<p><a href=\"https:\/\/www.eldiario.es\/agricola\/agricultura\/mujeres-espanolas-demandas-instituciones-comunitarias_0_825917547.html\">Las mujeres rurales espa\u00f1olas llevan su voz cargada de demandas a instituciones comunitarias&#8230;<\/a>&#8211; <a href=\"http:\/\/eldiario.es\">eldiario.es<\/a><\/p>\n<p><a href=\"http:\/\/www.elmundo.es\/economia\/macroeconomia\/2018\/10\/17\/5bc3505522601d6e268b4623.html\">Karen Ward (JP Morgan): \u00abSeguiremos viendo reformas en Espa\u00f1a\u00bb<\/a> \u2013 El Mundo<\/p>\n<p><a href=\"https:\/\/www.diariosur.es\/economia\/romper-estereotipos-genero-20181017000459-ntvo.html\">Romper con los estereotipos de g\u00e9nero en las empresas, una ventaja &#8230;<\/a>&#8211; Sur Digital<\/p>\n<p><strong>Actualidad<\/strong><\/p>\n<p><a href=\"http:\/\/www.mujeremprendedora.net\/xxx-aniversario-mujer-fuerzas-armadas\/\">XXX aniversario de la de la mujer en las Fuerzas Armadas<\/a> \u2013 Mujeremprendededora.net<\/p>\n<p><a href=\"http:\/\/www.mujeremprendedora.net\/girlsgetequal-continua-iniciativa-tomas-poder\/\">#GirlsGetEqual continua con su iniciativa \u201ctomas de poder\u201d<\/a> \u2013 Mujeremprendededora.net<\/p>\n<p><a href=\"https:\/\/www.elempresario.com\/noticias\/estilo_vida\/2018\/10\/17\/la_mujer_del_siglo_xxi_empoderada_segura_sexy_actual_113906_1100.html\">La mujer del siglo XXI: empoderada, segura, sexy y actual<\/a>&#8211; El Empresario<\/p>\n<p><strong>Violencia<\/strong><strong>s<\/strong><\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=0ahUKEwjworScpI3eAhXwlYsKHdPIA2QQqQIIJygAMAA&amp;url=https%3A%2F%2Fwww.zamora24horas.com%2Ftexto-diario%2Fmostrar%2F1211107%2Fcongreso-quiere-violencia-machista-sea-especialidad-juridica-equiparable-penal-menores&amp;usg=AOvVaw36Wp4xY0Qk8c8GpnVHEE8n\">El Congreso quiere que la violencia machista sea una especialidad &#8230;<\/a>&#8211; Zamora 24 Horas<\/p>\n<p><a href=\"https:\/\/www.publico.es\/sociedad\/violencia-genero-disminuyen-denuncias-incrementan-condenas-violencia-machista.html\">Disminuyen la denuncias y se incrementan la condenas por violencia &#8230;<\/a>&#8211; P\u00fablico<\/p>\n<p><a href=\"https:\/\/www.publico.es\/sociedad\/violencia-machista-hombre-hiere-gravedad-pareja-botella-delante-hijo-murcia.html\">Un hombre hiere de gravedad a su mujer con una botella delante de su hijo y se suicida<\/a>&#8211; P\u00fablico<\/p>\n<p><strong>Ciencia y Cultura<\/strong><\/p>\n<p><a href=\"https:\/\/elpais.com\/elpais\/2018\/10\/15\/ciencia\/1539599537_649940.html\">\u00bfCu\u00e1ntos seres vivos no humanos hay en el cuerpo de una persona?<\/a> \u2013 El Pa\u00eds<\/p>\n<p><u><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=https:\/\/www.elconfidencial.com\/cultura\/2018-10-16\/premio-nacional-comic-ana-penyas-estamos-todas-bien_1631001\/&amp;ct=ga&amp;cd=CAEYGioTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNHy3-ublS84vZcmUe9NGbar1JBv0g\">Ana Penyas, primera mujer en ganar el Premio Nacional del C\u00f3mic <\/a>&#8211;<\/u> El Confidencial<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=https:\/\/www.lavanguardia.com\/vida\/20181016\/452393641056\/treinta-productoras-espanolas-debatiran-en-ii-foro-de-mujeres-de-cine-espanol.html&amp;ct=ga&amp;cd=CAEYFCoTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNF-XrQLiYLasFhA4cbGrj-nLLB7Vw\">Treinta productoras espa\u00f1olas debatir\u00e1n en II Foro de Mujeres de Cine Espa\u00f1ol <\/a>&#8211; La Vanguardia<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=https:\/\/elpais.com\/ccaa\/2018\/10\/16\/catalunya\/1539711532_765614.html&amp;ct=ga&amp;cd=CAEYKyoTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNEVn9cP1x5KoD0k7AksTicxFj5Emg\">La Bienal del Pensamiento arranca con fuerza en Barcelona <\/a>\u2013El Pa\u00eds<\/p>\n<p><a href=\"https:\/\/elasombrario.com\/dorothea-tanning-artista-crear-fantasias-102-anos\/\">Dorothea Tanning, la artista que no dej\u00f3 de crear fantas\u00edas hasta los 102 a\u00f1os<\/a>&#8211; P\u00fablico<\/p>\n<p><a href=\"http:\/\/www.mujeremprendedora.net\/iii-dia-escritoras-visibiliza-rebelion-literaria-de-mujeres\/\">El III D\u00eda de las Escritoras visibiliza la \u2018rebeli\u00f3n\u2019 literaria de las mujeres<\/a>\u2013 Mujeremprendededora.net<\/p>\n<p><a href=\"https:\/\/www.eldiario.es\/cultura\/libros\/Planeta-hombres-premio-dotado-espanolas_0_825567674.html\">Un Planeta de hombres: el premio mejor dotado de las letras &#8230;<\/a>&#8211; eldiario.es<\/p>\n<p><strong>Deporte<\/strong><\/p>\n<p><u><a href=\"https:\/\/www.google.com\/url?rct=j&amp;sa=t&amp;url=http:\/\/cadenaser.com\/emisora\/2018\/10\/16\/radio_pamplona\/1539710902_159461.html&amp;ct=ga&amp;cd=CAEYMCoTMTAwMzg5MjI5NTQzMDU2Njk3MDIZYzAzNzJlYmMyZmVhZGE1OTplczplczpFUw&amp;usg=AFQjCNEvU-QiyDd5cmNyMhwWf3EWeTBUZA\">Primer congreso Deporte y Mujer <\/a><\/u>&#8211; Cadena SER<\/p>\n<p><a href=\"https:\/\/www.lasprovincias.es\/culturas\/anabel-medina-extenista-20181017003231-ntvo.html\">Anabel Medina, extenista y capitana del equipo espa\u00f1ol de Copa &#8230;<\/a>&#8211; Las Provincia<\/p>\n<p>[\/toggle]<\/p>\n<p>[toggle type=\u00bbfirst\u00bb title=\u00bbInternacional\u00bb]<\/p>\n<p><a href=\"http:\/\/www.elmundo.es\/internacional\/2018\/10\/17\/5bc704fc46163ff04b8b45f3.html\">Christine Lagarde, directora del FMI, cancela su viaje al foro econ\u00f3mico de Arabia Saud\u00ed<\/a> \u2013 El Mundo<\/p>\n<p><a href=\"https:\/\/www.elespectador.com\/noticias\/el-mundo\/igualdad-en-etiopia-mujeres-compondran-la-mitad-del-nuevo-gobierno-articulo-818252\">Igualdad en Etiop\u00eda: Mujeres compondr\u00e1n la mitad del nuevo Gobierno<\/a>&#8211; ElEspectador.com<\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=66&amp;ved=0ahUKEwjzn4vVp43eAhWOiIsKHZxaD8I4PBCpAgg1KAAwBQ&amp;url=https%3A%2F%2Fwww.eldiario.es%2Ftheguardian%2Fmujeres-apoyan-Bolsonaro-sentido-feminismo_0_825567705.html&amp;usg=AOvVaw30_4jlzFSKGxhaxJh-Ncgy\">Las mujeres que apoyan a Bolsonaro: \u00abNo le veo ning\u00fan sentido al feminismo\u201d&#8230;<\/a>&#8211;<a href=\"http:\/\/eldiario.es\">eldiario.es<\/a><\/p>\n<p><a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=newssearch&amp;cd=87&amp;ved=0ahUKEwi5pbG2qI3eAhVKhqYKHTy8DlM4UBCpAgg4KAAwBg&amp;url=https%3A%2F%2Fwww.eldiario.es%2Fsociedad%2FParaguay-Ciudad-Mujer-Movil-mujeres_0_825568443.html&amp;usg=AOvVaw0YsaTHZz0AyyBv-iwtGcOC\">Paraguay pone en marcha la Ciudad Mujer M\u00f3vil para llegar a m\u00e1s &#8230;<\/a>&#8211;<a href=\"http:\/\/eldiario.es\">eldiario.es<\/a><\/p>\n<p><a href=\"https:\/\/elpais.com\/internacional\/2018\/10\/16\/actualidad\/1539700757_009244.html\">La emancipaci\u00f3n de las afganas no sale de las grandes ciudades<\/a>\u2013El Pa\u00eds<\/p>\n<p><a href=\"http:\/\/www.diariovasco.com\/agencias\/201810\/16\/parlamentarias-europeas-sufrido-violencia-1273990.html\">El 85 % de las parlamentarias europeas han sufrido violencia &#8230;<\/a>&#8211; Diario Vasco<\/p>\n<p><a href=\"https:\/\/www.cuatro.com\/deportes\/iran-mujeres-futbol-estadio-igualdad-azadi_0_2644425020.html\">El vergonzoso permiso de Ir\u00e1n a las mujeres para ir al f\u00fatbol: solo &#8230;<\/a>-Cuatro<\/p>\n<p><a href=\"https:\/\/elpais.com\/cultura\/2018\/10\/16\/actualidad\/1539724265_963784.html\">La escritora norirlandesa Anna Burns gana el premio literario Man Booker<\/a> \u2013 El Pa\u00eds<\/p>\n<p><a href=\"https:\/\/elpais.com\/cultura\/2018\/10\/16\/actualidad\/1539681745_536232.html\">Cien a\u00f1os de Rita Hayworth, el icono que asfixi\u00f3 a Margarita Cansino<\/a>\u2013El Pa\u00eds<\/p>\n<p>[\/toggle]<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso aprueba multar a las empresas que no tengan <a href=\"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[298,623],"tags":[],"class_list":["post-14226","post","type-post","status-publish","format-standard","hentry","category-newsletter","category-nwl-2-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noticias Info CKL n\u00ba 2.214-17\/10\/18-Comunica con perspectiva de g\u00e9nero<\/title>\n<meta name=\"description\" content=\"Comunicar con perspectiva de g\u00e9nero: El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Ana Penyas Premio Nacional del C\u00f3mic...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noticias Info CKL n\u00ba 2.214-17\/10\/18-Comunica con perspectiva de g\u00e9nero\" \/>\n<meta property=\"og:description\" content=\"Comunicar con perspectiva de g\u00e9nero: El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Ana Penyas Premio Nacional del C\u00f3mic...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/\" \/>\n<meta property=\"og:site_name\" content=\"CKL Comunicaciones\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-17T12:02:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T15:40:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cklcomunicaciones.es\/coop\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ckl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ckl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/\"},\"author\":{\"name\":\"ckl\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/#\\\/schema\\\/person\\\/ea52d17cb71ca75305f8a1b1b50f81fc\"},\"headline\":\"Noticias Info CKL n\u00ba 2.214-17\\\/10\\\/18\",\"datePublished\":\"2018-10-17T12:02:30+00:00\",\"dateModified\":\"2025-01-17T15:40:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/\"},\"wordCount\":1095,\"image\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.cklcomunicaciones.es\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg\",\"articleSection\":[\"Newsletter\",\"Nwl v2.0\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/\",\"url\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/\",\"name\":\"Noticias Info CKL n\u00ba 2.214-17\\\/10\\\/18-Comunica con perspectiva de g\u00e9nero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.cklcomunicaciones.es\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg\",\"datePublished\":\"2018-10-17T12:02:30+00:00\",\"dateModified\":\"2025-01-17T15:40:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/#\\\/schema\\\/person\\\/ea52d17cb71ca75305f8a1b1b50f81fc\"},\"description\":\"Comunicar con perspectiva de g\u00e9nero: El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Ana Penyas Premio Nacional del C\u00f3mic...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.cklcomunicaciones.es\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg\",\"contentUrl\":\"http:\\\/\\\/www.cklcomunicaciones.es\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/noticias-info-ckl-no-2-214-17-10-18\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias Info CKL n\u00ba 2.214-17\\\/10\\\/18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/#website\",\"url\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/\",\"name\":\"CKL Comunicaciones\",\"description\":\"Sitio web de CKL Comunicaciones coop , la consultora de comunicaci\u00f3n y estrategia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/#\\\/schema\\\/person\\\/ea52d17cb71ca75305f8a1b1b50f81fc\",\"name\":\"ckl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c82db564e8a669bf6023357a157b9dc4780f4d4c618f2ad1d71a6a5dede45057?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c82db564e8a669bf6023357a157b9dc4780f4d4c618f2ad1d71a6a5dede45057?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c82db564e8a669bf6023357a157b9dc4780f4d4c618f2ad1d71a6a5dede45057?s=96&d=mm&r=g\",\"caption\":\"ckl\"},\"url\":\"https:\\\/\\\/cklcomunicaciones.es\\\/coop\\\/author\\\/cklcomunicaciones\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noticias Info CKL n\u00ba 2.214-17\/10\/18-Comunica con perspectiva de g\u00e9nero","description":"Comunicar con perspectiva de g\u00e9nero: El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Ana Penyas Premio Nacional del C\u00f3mic...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/","og_locale":"es_ES","og_type":"article","og_title":"Noticias Info CKL n\u00ba 2.214-17\/10\/18-Comunica con perspectiva de g\u00e9nero","og_description":"Comunicar con perspectiva de g\u00e9nero: El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Ana Penyas Premio Nacional del C\u00f3mic...","og_url":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/","og_site_name":"CKL Comunicaciones","article_published_time":"2018-10-17T12:02:30+00:00","article_modified_time":"2025-01-17T15:40:34+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/cklcomunicaciones.es\/coop\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero.jpg","type":"image\/jpeg"}],"author":"ckl","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ckl","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#article","isPartOf":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/"},"author":{"name":"ckl","@id":"https:\/\/cklcomunicaciones.es\/coop\/#\/schema\/person\/ea52d17cb71ca75305f8a1b1b50f81fc"},"headline":"Noticias Info CKL n\u00ba 2.214-17\/10\/18","datePublished":"2018-10-17T12:02:30+00:00","dateModified":"2025-01-17T15:40:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/"},"wordCount":1095,"image":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cklcomunicaciones.es\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg","articleSection":["Newsletter","Nwl v2.0"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/","url":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/","name":"Noticias Info CKL n\u00ba 2.214-17\/10\/18-Comunica con perspectiva de g\u00e9nero","isPartOf":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#primaryimage"},"image":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cklcomunicaciones.es\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg","datePublished":"2018-10-17T12:02:30+00:00","dateModified":"2025-01-17T15:40:34+00:00","author":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/#\/schema\/person\/ea52d17cb71ca75305f8a1b1b50f81fc"},"description":"Comunicar con perspectiva de g\u00e9nero: El Congreso aprueba multar a las empresas que no tengan mujeres en los consejos-Ana Penyas Premio Nacional del C\u00f3mic...","breadcrumb":{"@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#primaryimage","url":"http:\/\/www.cklcomunicaciones.es\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg","contentUrl":"http:\/\/www.cklcomunicaciones.es\/wp-content\/uploads\/2018\/03\/CKL_comunicacion-con-perspetiva-de-genero-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cklcomunicaciones.es\/coop\/noticias-info-ckl-no-2-214-17-10-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cklcomunicaciones.es\/coop\/"},{"@type":"ListItem","position":2,"name":"Noticias Info CKL n\u00ba 2.214-17\/10\/18"}]},{"@type":"WebSite","@id":"https:\/\/cklcomunicaciones.es\/coop\/#website","url":"https:\/\/cklcomunicaciones.es\/coop\/","name":"CKL Comunicaciones","description":"Sitio web de CKL Comunicaciones coop , la consultora de comunicaci\u00f3n y estrategia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cklcomunicaciones.es\/coop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/cklcomunicaciones.es\/coop\/#\/schema\/person\/ea52d17cb71ca75305f8a1b1b50f81fc","name":"ckl","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c82db564e8a669bf6023357a157b9dc4780f4d4c618f2ad1d71a6a5dede45057?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c82db564e8a669bf6023357a157b9dc4780f4d4c618f2ad1d71a6a5dede45057?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c82db564e8a669bf6023357a157b9dc4780f4d4c618f2ad1d71a6a5dede45057?s=96&d=mm&r=g","caption":"ckl"},"url":"https:\/\/cklcomunicaciones.es\/coop\/author\/cklcomunicaciones\/"}]}},"_links":{"self":[{"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/posts\/14226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/comments?post=14226"}],"version-history":[{"count":0,"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/posts\/14226\/revisions"}],"wp:attachment":[{"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/media?parent=14226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/categories?post=14226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cklcomunicaciones.es\/coop\/wp-json\/wp\/v2\/tags?post=14226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}